{"id":25,"date":"2019-03-26T00:29:09","date_gmt":"2019-03-25T15:29:09","guid":{"rendered":"http:\/\/www.nagaokaut.ac.jp\/j\/wise\/?page_id=25"},"modified":"2019-03-26T00:29:25","modified_gmt":"2019-03-25T15:29:25","slug":"model","status":"publish","type":"page","link":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/model\/","title":{"rendered":"\u5b66\u4fee\u30e2\u30c7\u30eb"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":23,"menu_order":62,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u5b66\u4fee\u30e2\u30c7\u30eb - \u9577\u5ca1\u6280\u8853\u79d1\u5b66\u5927\u5b66 \u5353\u8d8a\u5927\u5b66\u9662\u30d7\u30ed\u30b0\u30e9\u30e0 \u30b0\u30ed\u30fc\u30d0\u30eb\u8d85\u5b9f\u8df5\u30eb\u30fc\u30c8\u30c6\u30af\u30ce\u30ed\u30b8\u30fc\u30d7\u30ed\u30b0\u30e9\u30e0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/model\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u5b66\u4fee\u30e2\u30c7\u30eb - \u9577\u5ca1\u6280\u8853\u79d1\u5b66\u5927\u5b66 \u5353\u8d8a\u5927\u5b66\u9662\u30d7\u30ed\u30b0\u30e9\u30e0 \u30b0\u30ed\u30fc\u30d0\u30eb\u8d85\u5b9f\u8df5\u30eb\u30fc\u30c8\u30c6\u30af\u30ce\u30ed\u30b8\u30fc\u30d7\u30ed\u30b0\u30e9\u30e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/model\/\" \/>\n<meta property=\"og:site_name\" content=\"\u9577\u5ca1\u6280\u8853\u79d1\u5b66\u5927\u5b66 \u5353\u8d8a\u5927\u5b66\u9662\u30d7\u30ed\u30b0\u30e9\u30e0 \u30b0\u30ed\u30fc\u30d0\u30eb\u8d85\u5b9f\u8df5\u30eb\u30fc\u30c8\u30c6\u30af\u30ce\u30ed\u30b8\u30fc\u30d7\u30ed\u30b0\u30e9\u30e0\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-25T15:29:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/curriculum\\\/model\\\/\",\"url\":\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/curriculum\\\/model\\\/\",\"name\":\"\u5b66\u4fee\u30e2\u30c7\u30eb - \u9577\u5ca1\u6280\u8853\u79d1\u5b66\u5927\u5b66 \u5353\u8d8a\u5927\u5b66\u9662\u30d7\u30ed\u30b0\u30e9\u30e0 \u30b0\u30ed\u30fc\u30d0\u30eb\u8d85\u5b9f\u8df5\u30eb\u30fc\u30c8\u30c6\u30af\u30ce\u30ed\u30b8\u30fc\u30d7\u30ed\u30b0\u30e9\u30e0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/#website\"},\"datePublished\":\"2019-03-25T15:29:09+00:00\",\"dateModified\":\"2019-03-25T15:29:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/curriculum\\\/model\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/curriculum\\\/model\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/curriculum\\\/model\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30ab\u30ea\u30ad\u30e5\u30e9\u30e0\",\"item\":\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/curriculum\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u5b66\u4fee\u30e2\u30c7\u30eb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/#website\",\"url\":\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/\",\"name\":\"\u9577\u5ca1\u6280\u8853\u79d1\u5b66\u5927\u5b66 \u5353\u8d8a\u5927\u5b66\u9662\u30d7\u30ed\u30b0\u30e9\u30e0 \u30b0\u30ed\u30fc\u30d0\u30eb\u8d85\u5b9f\u8df5\u30eb\u30fc\u30c8\u30c6\u30af\u30ce\u30ed\u30b8\u30fc\u30d7\u30ed\u30b0\u30e9\u30e0\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wise.nagaokaut.ac.jp\\\/j\\\/wise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u5b66\u4fee\u30e2\u30c7\u30eb - \u9577\u5ca1\u6280\u8853\u79d1\u5b66\u5927\u5b66 \u5353\u8d8a\u5927\u5b66\u9662\u30d7\u30ed\u30b0\u30e9\u30e0 \u30b0\u30ed\u30fc\u30d0\u30eb\u8d85\u5b9f\u8df5\u30eb\u30fc\u30c8\u30c6\u30af\u30ce\u30ed\u30b8\u30fc\u30d7\u30ed\u30b0\u30e9\u30e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/model\/","og_locale":"ja_JP","og_type":"article","og_title":"\u5b66\u4fee\u30e2\u30c7\u30eb - \u9577\u5ca1\u6280\u8853\u79d1\u5b66\u5927\u5b66 \u5353\u8d8a\u5927\u5b66\u9662\u30d7\u30ed\u30b0\u30e9\u30e0 \u30b0\u30ed\u30fc\u30d0\u30eb\u8d85\u5b9f\u8df5\u30eb\u30fc\u30c8\u30c6\u30af\u30ce\u30ed\u30b8\u30fc\u30d7\u30ed\u30b0\u30e9\u30e0","og_url":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/model\/","og_site_name":"\u9577\u5ca1\u6280\u8853\u79d1\u5b66\u5927\u5b66 \u5353\u8d8a\u5927\u5b66\u9662\u30d7\u30ed\u30b0\u30e9\u30e0 \u30b0\u30ed\u30fc\u30d0\u30eb\u8d85\u5b9f\u8df5\u30eb\u30fc\u30c8\u30c6\u30af\u30ce\u30ed\u30b8\u30fc\u30d7\u30ed\u30b0\u30e9\u30e0","article_modified_time":"2019-03-25T15:29:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/model\/","url":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/model\/","name":"\u5b66\u4fee\u30e2\u30c7\u30eb - \u9577\u5ca1\u6280\u8853\u79d1\u5b66\u5927\u5b66 \u5353\u8d8a\u5927\u5b66\u9662\u30d7\u30ed\u30b0\u30e9\u30e0 \u30b0\u30ed\u30fc\u30d0\u30eb\u8d85\u5b9f\u8df5\u30eb\u30fc\u30c8\u30c6\u30af\u30ce\u30ed\u30b8\u30fc\u30d7\u30ed\u30b0\u30e9\u30e0","isPartOf":{"@id":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/#website"},"datePublished":"2019-03-25T15:29:09+00:00","dateModified":"2019-03-25T15:29:25+00:00","breadcrumb":{"@id":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/model\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/model\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/model\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/"},{"@type":"ListItem","position":2,"name":"\u30ab\u30ea\u30ad\u30e5\u30e9\u30e0","item":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/curriculum\/"},{"@type":"ListItem","position":3,"name":"\u5b66\u4fee\u30e2\u30c7\u30eb"}]},{"@type":"WebSite","@id":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/#website","url":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/","name":"\u9577\u5ca1\u6280\u8853\u79d1\u5b66\u5927\u5b66 \u5353\u8d8a\u5927\u5b66\u9662\u30d7\u30ed\u30b0\u30e9\u30e0 \u30b0\u30ed\u30fc\u30d0\u30eb\u8d85\u5b9f\u8df5\u30eb\u30fc\u30c8\u30c6\u30af\u30ce\u30ed\u30b8\u30fc\u30d7\u30ed\u30b0\u30e9\u30e0","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":3,"href":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":9116,"href":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/wp-json\/wp\/v2\/pages\/25\/revisions\/9116"}],"up":[{"embeddable":true,"href":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/wp-json\/wp\/v2\/pages\/23"}],"wp:attachment":[{"href":"https:\/\/wise.nagaokaut.ac.jp\/j\/wise\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}